{"id":84466,"date":"2019-01-25T14:47:14","date_gmt":"2019-01-25T17:47:14","guid":{"rendered":"http:\/\/www.elsindical.com.ar\/notas\/?p=84466"},"modified":"2019-01-25T14:47:14","modified_gmt":"2019-01-25T17:47:14","slug":"easy-estafa-e-impunidad","status":"publish","type":"post","link":"https:\/\/www.elsindical.com.ar\/notas\/easy-estafa-e-impunidad\/","title":{"rendered":"Easy \u00bfestafa e impunidad?"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"http:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2019\/01\/Logo_Easy_Cencosud.jpg\" alt=\"\" class=\"wp-image-84467\" srcset=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2019\/01\/Logo_Easy_Cencosud.jpg 300w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2019\/01\/Logo_Easy_Cencosud-150x150.jpg 150w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2019\/01\/Logo_Easy_Cencosud-50x50.jpg 50w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">   Cuando una empresa de la relevancia que tiene Easy, vende productos con su aval, como es el caso de la marca Datrak, uno conf\u00eda en que el producto de m\u00ednima funciona, m\u00e1s all\u00e1 de la calidad y duraci\u00f3n del mismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora bien, cuando el producto adquirido es desenvuelto y retirado de la caja y lo primero que ocurre es que el supuesto acr\u00edlico de la linterna se cae, para luego al querer usar el aparato (un compresor de 12V) no funcione, entonces claramente es una estafa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este tipo de compras, uno no llega al domicilio y prueba a desinflar e inflar las ruedas, tampoco en la sucursal hacen alguna prueba con el compresor, as\u00ed las cosas, uno por confiado lo guarda en el ba\u00fal del auto por si una emergencia hace que sea necesario inflar alguna rueda, se imaginan la decepci\u00f3n si al pensar en que esa compra hoy nos saca del paso no funciona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la mejor voluntad y sinceridad uno hace el reclamo, advierte que pasaron varios meses de la compra, pero que no se trata de reclamar la garant\u00eda, ya que el producto no funcion\u00f3 nunca, las excusas son varias, todas tendientes a supuestas condiciones que no le son comunicadas al comprador, que son contrarias a la Ley 24.240 de Defensa del Consumidor, la primera y rid\u00edcula que uno debe acreditar que el producto fue comprado en Easy, yo me pregunto, la empresa no tiene inventariado los productos? cuando uno paga en la caja si usan el c\u00f3digo de barras es porque est\u00e1 inventariado, en \u00e9poca de una inform\u00e1tica avanzada ellos no pueden saber si el producto fue comprado a la firma?.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para complicar m\u00e1s el reclamo, solicitan que uno posea el ticket en condiciones y que no hayan transcurrido m\u00e1s de 6 meses de la compra porque nadie sabe d\u00f3nde se archivan las operaciones, algo ins\u00f3lito por las obligaciones fiscales, pero bueno, es lo que ellos informan, en definitiva si compras alg\u00fan producto que no necesitas usar igualmente proba su funcionamiento, nunca conf\u00edes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiz\u00e1s un dato sugerente es que el producto \u00abCompresor de aire para el autom\u00f3vil\u00bb desapareci\u00f3 de las sucursales de la firma, aunque nadie supo explicar la falta de stock, en situaciones as\u00ed, generalmente el producto viene fallado de f\u00e1brica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando ped\u00eds el Libro de Reclamos, tambi\u00e9n uno se encuentra con que el mismo no est\u00e1 rubricado por ninguna autoridad otro hecho contrario a la Ley de Defensa del Consumidor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tuviste inconvenientes con la empresa, podes escribir al correo del diario y contarnos <a href=\"editor@elsindical.com.ar\">editor@elsindical.com.ar<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por Marcelo Ricardo Hawrylciw<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"http:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2019\/01\/compresor-para-auto-Datrak-768x1024.jpg\" alt=\"\" class=\"wp-image-84468\" srcset=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2019\/01\/compresor-para-auto-Datrak-768x1024.jpg 768w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2019\/01\/compresor-para-auto-Datrak-225x300.jpg 225w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2019\/01\/compresor-para-auto-Datrak.jpg 864w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Cuando una empresa de la relevancia que tiene Easy, vende productos con su aval, como es el caso de la marca Datrak, uno conf\u00eda en que el producto de m\u00ednima funciona, m\u00e1s all\u00e1 de la calidad y duraci\u00f3n del mismo. Ahora bien, cuando el producto adquirido es desenvuelto y retirado de la caja y lo&hellip;<\/p>\n","protected":false},"author":1,"featured_media":84467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[30299,22020,3702,30300],"class_list":["post-84466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-denuncias","tag-compresor","tag-denuncias","tag-easy","tag-ley-de-defensa-del-consumidor"],"_links":{"self":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/84466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/comments?post=84466"}],"version-history":[{"count":1,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/84466\/revisions"}],"predecessor-version":[{"id":84469,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/84466\/revisions\/84469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media\/84467"}],"wp:attachment":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media?parent=84466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/categories?post=84466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/tags?post=84466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}