{"id":71151,"date":"2017-08-14T09:49:03","date_gmt":"2017-08-14T12:49:03","guid":{"rendered":"http:\/\/www.elsindical.com.ar\/notas\/?p=71151"},"modified":"2017-08-14T09:49:03","modified_gmt":"2017-08-14T12:49:03","slug":"graciela-beatriz-otero-la-docente-que-no-sabe","status":"publish","type":"post","link":"https:\/\/www.elsindical.com.ar\/notas\/graciela-beatriz-otero-la-docente-que-no-sabe\/","title":{"rendered":"Graciela Beatriz Otero la docente que no sabe"},"content":{"rendered":"<p><em>\u00a0<a href=\"http:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2017\/08\/Escuela-Secundaria-30-Gerli.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-71152\" src=\"http:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2017\/08\/Escuela-Secundaria-30-Gerli-300x223.jpg\" alt=\"\" width=\"300\" height=\"223\" srcset=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2017\/08\/Escuela-Secundaria-30-Gerli-300x223.jpg 300w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2017\/08\/Escuela-Secundaria-30-Gerli-404x300.jpg 404w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2017\/08\/Escuela-Secundaria-30-Gerli.jpg 531w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> Si hay un colmo, ese debe ser el que una docente y m\u00e1s una directora intente imponerle a un ciudadano una conducta supuestamente legal, cuando en realidad la se\u00f1ora docente, desconoce el contenido de la Ley electoral y por ende su conducta adem\u00e1s de pat\u00e9tica es contraria a la Ley.<\/em><\/p>\n<p>Las elecciones han dejado algo muy concreto m\u00e1s all\u00e1 de los resultados pol\u00edticos y es la enorme ignorancia que existe entre los ciudadanos, pero tambi\u00e9n entre las autoridades elegidas para actuar en las elecciones, incluso el personal de seguridad, polic\u00edas y de las fuerzas de seguridad, desconocen cu\u00e1l es su rol y simplemente se limitan a lo m\u00e1s sencillo, cumplir ordenes.<\/p>\n<p>Graciela Beatriz Otero es un muy mal ejemplo de lo que se espera de una docente con cargo jer\u00e1rquico, la directora es la m\u00e1xima autoridad de un establecimiento y si esta reconoce desconocer la Ley, con qu\u00e9 \u00e9tica puede exigir a los alumnos estudiar si ella no lo hace. En la Escuela Secundaria B\u00e1sica N\u00ba 30 de Gerli, ubicada en la calle Rep\u00fablica del L\u00edbano 1517, con correo electr\u00f3nico secundaria30avellaneda@yahoo.com.ar, el domingo 13 de agosto d\u00eda de las PASO faltaba el presidente de la mesa 274, con lo cual lo primero que se les ocurri\u00f3 a unos colaboradores y a la se\u00f1ora Otero obligar al primero que concurra a votar en esa mesa en reemplazo del presidente ausente y de los suplentes de los cuales nadie ten\u00eda forma de comunicarse, la escuela abri\u00f3 a las 08:07 y todo estaba mal organizado.<\/p>\n<p>Luego de que un personaje que no se quiso identificar me dijera que me iban a dejar \u00abpor ir a votar temprano\u00bb, la directora me dijo que si yo aduc\u00eda cuestiones de salud para no quedarme iba a tener que hacer un acta e informar a lo que le dije que no ten\u00eda problema y firme el acta declinando el ofrecimiento, posteriormente tanto Otero como otros colaboradores se dedicaron a imponerle a los que llegaban el reemplazo de los ausentes dici\u00e9ndoles que se trataba de una carga p\u00fablica y que de no hacerlo informar\u00edan a los polic\u00edas presentes, a m\u00ed me toco quedarme esperando a que me dejen votar por decisi\u00f3n de Otero en castigo por no haber aceptado ser presidente de la mesa donde deb\u00eda votar, le pregunte si estaba segura de lo que estaba haciendo y me dijo que s\u00ed que as\u00ed es la Ley a lo que le pregunte si me pod\u00eda decir el n\u00famero de la Ley Electoral debiendo reconocer que no lo sab\u00eda y que no la hab\u00eda le\u00eddo pero que ella se gu\u00eda por lo que le dijeron y que iba a consultar con el Comando Electoral.<\/p>\n<p>Luego de que supuestamente llamara al Comando Electoral y vaya uno a saber por quien fue atendida, me dijo que ella estaba haciendo las cosas bien y que iba a tener que esperar para votar porque ella no quer\u00eda reemplazar los ausentes con gente que no votara en esa mesa, ya que hab\u00eda personas dispuestas a cubrir la ausencia pero no votaban en esa mesa y eso a Otero no le parec\u00eda correcto.<\/p>\n<p>Ley 19.945 modificada por Leyes Nros. 20.175, 22.838 y 22.864<\/p>\n<p>T\u00edtulo I, Cap\u00edtulo I, Art\u00edculo 10-<strong>Amparo del elector.\u00a0 <\/strong><em>El elector que se considere afectado en sus inmunidades, libertad o seguridad, o privado del ejercicio del sufragio podr\u00e1 solicitar amparo por s\u00ed, o por intermedio de cualquier persona en su nombre, por escrito o verbalmente, denunciando el hecho al juez electoral o al magistrado m\u00e1s pr\u00f3ximo o a cualquier funcionario nacional o provincial, quienes estar\u00e1n obligados a adoptar urgentemente las medidas conducentes para hacer cesar el impedimento, si fuere ilegal o arbitrario.<\/em><\/p>\n<p>Basado en este art\u00edculo le solicite al efectivo del Ej\u00e9rcito Argentino que cumpliera con su obligaci\u00f3n legal y acta mediante le informara a Otero que estaba violando la Ley, al sostener una medida caprichosa, luego de que el efectivo consultara apareci\u00f3 una de las suplentes y una hora despu\u00e9s los que ten\u00edamos la mesa 274 pod\u00edamos votar.<\/p>\n<p>Esto que parece un simple mal entendido tiene una gravedad que nadie le da relevancia y son puntos que los ciudadanos deben saber para tener en cuenta.<\/p>\n<div>La realidad es que nadie te puede obligar a que te quedes como autoridad de mesa el d\u00eda de la elecci\u00f3n si las personas que fueron designadas no concurrieron. Dice el C\u00f3digo Electoral Nacional al respecto:<\/div>\n<div><\/div>\n<div>\n<div><i>Art\u00edculo 75. &#8211; Designaci\u00f3n de las autoridades. El <b>juzgado federal con competencia electoral<\/b> nombrar\u00e1 a los presidentes y suplentes para cada mesa, con una antelaci\u00f3n no menor de <b>treinta (30) d\u00edas a la fecha de las elecciones primarias<\/b> debiendo ratificar tal designaci\u00f3n para las elecciones generales.<\/i><\/div>\n<div><i>\u00a0<\/i><\/div>\n<div><i>Las autoridades de mesa deber\u00e1n figurar en el padr\u00f3n de la mesa para la cual sean designados.<\/i><\/div>\n<div><i>\u00a0<\/i><\/div>\n<div><i>Las notificaciones de designaci\u00f3n se cursar\u00e1n por el correo de la Naci\u00f3n o por intermedio de los servicios especiales de comunicaci\u00f3n que tengan los organismos de seguridad, ya sean nacionales o provinciales.<\/i><\/div>\n<div><i>\u00a0<\/i><\/div>\n<div><i>a) La excusaci\u00f3n de quienes resultaren designados se formular\u00e1 dentro de los tres (3) d\u00edas de notificados y \u00fanicamente podr\u00e1n invocarse razones de enfermedad o de fuerza mayor debidamente justificadas. Transcurrido este plazo s\u00f3lo podr\u00e1n excusarse por causas sobrevinientes, las que ser\u00e1n objeto de consideraci\u00f3n especial por la Junta;<\/i><\/div>\n<div><i>\u00a0<\/i><\/div>\n<div><i>b) Es causal de excepci\u00f3n el desempe\u00f1ar funciones de organizaci\u00f3n y\/o direcci\u00f3n de un partido pol\u00edtico y\/o ser candidato. Se acreditar\u00e1 mediante certificaci\u00f3n de las autoridades del respectivo partido;<\/i><\/div>\n<div><i>\u00a0<\/i><\/div>\n<div><i>c) A los efectos de la justificaci\u00f3n por los presidentes o suplentes de mesa de la enfermedad que les impida concurrir al acto electoral, solamente tendr\u00e1n validez los certificados extendidos por m\u00e9dicos de la sanidad nacional, provincial o municipal, en ese orden. En ausencia de los profesionales indicados, la certificaci\u00f3n podr\u00e1 ser extendida por un m\u00e9dico particular, pudiendo la Junta hacer verificar la exactitud de la misma por facultativos especiales. Si se comprobare falsedad, pasar\u00e1 los antecedentes al respectivo agente fiscal a los fines previstos en el art\u00edculo 132<\/i>.<\/div>\n<div><\/div>\n<\/div>\n<div>Entonces: el \u00fanico que te puede designar como presidente y suplente de una mesa en un acto electoral es un<b> juez federal con competencia electoral<\/b>. Ni la polic\u00eda, ni los gendarmes, ni las autoridades de otras mesas, ni el portero (?), ni nadie que est\u00e9 ah\u00ed te puede obligar a que seas autoridad de mesa.<\/div>\n<div><\/div>\n<div>Si el juez te nombra es obligatorio concurrir, ya que es una <b>carga p\u00fablica <\/b>(ojo: tambi\u00e9n pod\u00e9s ser voluntario). Si no concurr\u00eds, pod\u00e9s tener problemas:<\/div>\n<div><\/div>\n<div><i>Art\u00edculo 132. &#8211; No concurrencia o abandono de funciones electorales. Se penar\u00e1 con prisi\u00f3n de seis meses a dos a\u00f1os a los funcionarios creados por esta ley y a los electores designados para el desempe\u00f1o de funciones que sin causa justificada dejen de concurrir al lugar donde deban cumplirlas o hicieren abandono de ellas<\/i>.<\/div>\n<div><\/div>\n<div>\u00bfY si no van las autoridades el d\u00eda de la elecci\u00f3n, qu\u00e9 se hace? Bueno, esta es una pregunta que deber\u00eda haberse hecho el polic\u00eda que estaba increpando a la gente en el colegio. La respuesta a este interrogante la encontramos en el art. 81 del citado cuerpo normativo:<\/div>\n<div><\/div>\n<div>\n<div><i>Art\u00edculo 81. &#8211; Constituci\u00f3n de las mesas el d\u00eda del comicio. El d\u00eda se\u00f1alado para la elecci\u00f3n por la convocatoria respectiva deber\u00e1n encontrarse a las siete y cuarenta y cinco horas, en el local en que haya de funcionar la mesa, el presidente y sus suplentes, el empleado de correos con los documentos y \u00fatiles que menciona el art\u00edculo 66 y los agentes de polic\u00eda que las autoridades locales pondr\u00e1n a las \u00f3rdenes de las autoridades del comicio.<\/i><\/div>\n<div><i>\u00a0<\/i><\/div>\n<div><i>La autoridad policial adoptar\u00e1 las previsiones necesarias a fin de que los agentes afectados al servicio de custodia del acto conozcan los domicilios de las autoridades designadas para que en caso de inasistencia a la hora de apertura procedan a obtener por los medios m\u00e1s adecuados el comparendo de los titulares al desempe\u00f1o de sus funciones.<\/i><\/div>\n<div><i>\u00a0<\/i><\/div>\n<div><i>Si hasta las ocho y treinta horas no se hubieren presentado los designados, la autoridad policial y\/o el empleado postal har\u00e1 conocer tal circunstancia a su superior y \u00e9ste a su vez por la v\u00eda m\u00e1s r\u00e1pida a la Junta Electoral para que \u00e9sta tome las medidas conducentes a la habilitaci\u00f3n del comicio.<\/i><\/div>\n<div><i>\u00a0<\/i><\/div>\n<div><i>Las funciones que este art\u00edculo encomienda a la polic\u00eda son sin perjuicio de las que especialmente en cada elecci\u00f3n se establezcan en cuanto a su custodia y dem\u00e1s normas de seguridad<\/i>.<\/div>\n<div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Si hay un colmo, ese debe ser el que una docente y m\u00e1s una directora intente imponerle a un ciudadano una conducta supuestamente legal, cuando en realidad la se\u00f1ora docente, desconoce el contenido de la Ley electoral y por ende su conducta adem\u00e1s de pat\u00e9tica es contraria a la Ley. Las elecciones han dejado&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[461,26828,1662,26827,87,16752,565],"class_list":["post-71151","post","type-post","status-publish","format-standard","hentry","category-editorial","tag-avellaneda","tag-escuela-secundaria-basica-30","tag-gerli","tag-graciela-beatriz-otero","tag-ley","tag-paso","tag-votacion"],"_links":{"self":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/71151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/comments?post=71151"}],"version-history":[{"count":1,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/71151\/revisions"}],"predecessor-version":[{"id":71153,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/71151\/revisions\/71153"}],"wp:attachment":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media?parent=71151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/categories?post=71151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/tags?post=71151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}