{"id":44033,"date":"2014-07-09T18:13:33","date_gmt":"2014-07-09T21:13:33","guid":{"rendered":"http:\/\/www.elsindical.com.ar\/notas\/?p=44033"},"modified":"2014-07-09T18:13:33","modified_gmt":"2014-07-09T21:13:33","slug":"lomas-de-zamorarescatan-a-24-mujeres-explotadas-sexualmente-en-ingeniero-budge","status":"publish","type":"post","link":"https:\/\/www.elsindical.com.ar\/notas\/lomas-de-zamorarescatan-a-24-mujeres-explotadas-sexualmente-en-ingeniero-budge\/","title":{"rendered":"Lomas de Zamora:Rescatan a 24 mujeres explotadas sexualmente en Ingeniero Budge"},"content":{"rendered":"<p><em><a href=\"http:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2014\/07\/trata-en-Budge.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-44035\" src=\"http:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2014\/07\/trata-en-Budge-300x179.jpg\" alt=\"trata-en-Budge\" width=\"300\" height=\"179\" srcset=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2014\/07\/trata-en-Budge-300x179.jpg 300w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2014\/07\/trata-en-Budge-500x298.jpg 500w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2014\/07\/trata-en-Budge.jpg 502w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Los operativos los realiz\u00f3 Prefectura Naval junto a especialistas del Ministerio de Justicia y Derechos Humanos de la Naci\u00f3n. Los dos locales \u2013 que funcionaban como parrillas \u2013 se encontraban frente a una terminal de \u00f3mnibus, ubicada a pocas cuadras de Puente La Noria. \u201cLas v\u00edctimas se encontraban en una situaci\u00f3n de extrema vulnerabilidad\u201d, informaron fuentes oficiales. Algunas mujeres eran del barrio y otras de Rep\u00fablica Dominicana y Paraguay. Hab\u00edan llegado por un aviso publicitario enga\u00f1oso.<\/em><\/p>\n<p>Uno de las dos parrillas funcionaban como prost\u00edbulos, de donde la Justicia rescat\u00f3 a 234 v\u00edctimas de trata \u2013 ya hab\u00eda sido allanada hace tres a\u00f1os por una causa de explotaci\u00f3n sexual. Los dos locales funcionaban en Ingeniero Budge, frente a una terminal de \u00f3mnibus y a pocas cuadras del Puente La Noria.<\/p>\n<p>Los dos locales allanados funcionaban en Cosqu\u00edn, entre Azamor y Turner, un lugar de constante tr\u00e1nsito de personas por encontrarse frente a una terminal de \u00f3mnibus que incluso realizan viajes a pa\u00edses lim\u00edtrofes. El operativo se extendi\u00f3 desde la noche del jueves hasta la ma\u00f1ana del viernes \u00faltimo.<\/p>\n<p>Fuentes oficiales explicaron a <strong>DiarioConurbano<\/strong> que el n\u00famero de mujeres v\u00edctimas rescatadas en esos dos lugares fue de 24. \u201cLlegaron enga\u00f1adas por avisos publicados en el Diario Clar\u00edn. Todas se encontraban en situaci\u00f3n extrema vulnerabilidad\u201d, precisaron.<\/p>\n<p>En ambos lugares fueron detenidas 4 personas que regenteaban esos locales. En tanto, otra, con pedido de captura, se encuentra pr\u00f3fuga.<\/p>\n<p>\u201cLos lugares funcionaban como parrilla adelante y atr\u00e1s se ejerc\u00eda la prostituci\u00f3n. Todo en p\u00e9simas condiciones de salubridad e higiene\u201d, detallaron las mismas fuentes.<\/p>\n<p>El operativo de rescate fue llevado adelante por personal de la Prefectura Naval y por la Oficina de Rescate y Acompa\u00f1amiento a las V\u00edctimas de Trata, dependiente del Ministerio de Justicia y Derechos Humanos de la Naci\u00f3n.<\/p>\n<p>El allanamiento ordenado por el Juzgado Federal 2 de Lomas fue realizado no s\u00f3lo por el delito de trata sino tambi\u00e9n por la sospecha de que en el lugar se comercializaban estupefacientes.<\/p>\n<p>Seg\u00fan explicaron las fuentes consultadas \u201ca las mujeres se las amenazaba con hacerle algo a sus hijos y hab\u00eda todo un sistema de multas y pago de porcentaje a los regenteadores del lugar\u201d.<\/p>\n<p>Entre las mujeres rescatadas hab\u00eda algunas paraguayas y otras dominicanas. \u201cTodas llegaron por el aviso en el diario\u201d, se\u00f1alaron los informantes, a la vez que indicaron que otras j\u00f3venes viv\u00edan cerca de los lugares allanados en Ingeniero Budge.<\/p>\n<p>Los investigadores recordaron que una de las \u201cparrillas\u201d hab\u00eda sido allanada hace tres a\u00f1os. \u201cEn ese momento, el local funcionaba como un prost\u00edbulo, sin ninguna otra fachada\u201d, recordaron.<\/p>\n<p>Cuando Prefectura realiz\u00f3 el allanamiento, en los locales hab\u00eda cerca de 20 j\u00f3venes clientes, en avanzado estado de ebriedad. Esta situaci\u00f3n complic\u00f3 el desarrollo del procedimiento que finalmente se llev\u00f3 adelante.<\/p>\n<p>La denuncia original que permiti\u00f3 la investigaci\u00f3n lleg\u00f3 al Ministerio de Justicia y Derechos Humanos a trav\u00e9s de la l\u00ednea telef\u00f3nica 145, n\u00famero disponible para denunciar el delito de trata de personas.<\/p>\n<p>Los detenidos se encuentran a disposici\u00f3n del Juzgado Federal 2 de Lomas de Zamora, a cargo del Juez Carlos Alberto Ferreiro Pella.<\/p>\n<p>La justicia federal de Lomas de Zamora, deber\u00eda investigar c\u00f3mo es posible que ni la polic\u00eda bonaerense, ni la polic\u00eda federal (con delegaci\u00f3n propia en Lomas de Zamora para delitos federales), ni los funcionarios municipales a los que no se les escapa ning\u00fan negocio, no ten\u00edan conocimiento de los lugares y lo que en ellos ocurr\u00eda, teniendo en cuenta que son de f\u00e1cil acceso y muy concurridos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los operativos los realiz\u00f3 Prefectura Naval junto a especialistas del Ministerio de Justicia y Derechos Humanos de la Naci\u00f3n. Los dos locales \u2013 que funcionaban como parrillas \u2013 se encontraban frente a una terminal de \u00f3mnibus, ubicada a pocas cuadras de Puente La Noria. \u201cLas v\u00edctimas se encontraban en una situaci\u00f3n de extrema vulnerabilidad\u201d, informaron&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[746,19222,744,59,1328],"class_list":["post-44033","post","type-post","status-publish","format-standard","hentry","category-policiales","tag-ingeniero-budge","tag-juzgado-federal-2-de-lomas-de-zamora","tag-lomas-de-zamora","tag-mujeres","tag-prostibulos"],"_links":{"self":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/44033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/comments?post=44033"}],"version-history":[{"count":2,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/44033\/revisions"}],"predecessor-version":[{"id":44036,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/44033\/revisions\/44036"}],"wp:attachment":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media?parent=44033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/categories?post=44033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/tags?post=44033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}