{"id":394,"date":"2009-09-17T08:11:36","date_gmt":"2009-09-17T11:11:36","guid":{"rendered":"http:\/\/www.elsindical.com.ar\/notas\/?p=394"},"modified":"2017-05-26T09:50:44","modified_gmt":"2017-05-26T12:50:44","slug":"drogas-y-narcotrafico-lo-que-no-se-dice","status":"publish","type":"post","link":"https:\/\/www.elsindical.com.ar\/notas\/drogas-y-narcotrafico-lo-que-no-se-dice\/","title":{"rendered":"Drogas y narcotr\u00e1fico, lo que no se dice"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-395\" title=\"Christian-Sanz\" src=\"http:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2009\/09\/Christian-Sanz.jpg\" alt=\"Christian-Sanz\" width=\"236\" height=\"227\" \/>El pr\u00f3ximo viernes 18 de septiembre a las 18 hs. el periodista Christian Sanz disertar\u00e1 en el <em>Instituto de Investigaciones Hist\u00f3ricas Tte. Gral. Juan Domingo Per\u00f3n <\/em>acerca del siguiente t\u00f3pico: <strong>narcotr\u00e1fico y drogas, lo que no se dice<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0 All\u00ed, Sanz hablar\u00e1 de los efectos de las drogas en general, qui\u00e9nes son los responsables de que haya crecido el tr\u00e1fico de estupefacientes en la Argentina y por qu\u00e9 se despenaliz\u00f3 su tenencia.<br \/>\n\u00a0\u00a0\u00a0 El instituto se encuentra ubicado en la calle Sarmiento 1469 3\u00ba A, de la Ciudad de Buenos Aires.<br \/>\n\u00a0\u00a0\u00a0 La entrada ser\u00e1 libre y gratuita y se permitir\u00e1 la pregunta de los asistentes. Los esperamos.<\/p>\n<p style=\"text-align: justify;\"><strong>Redacci\u00f3n de <em>Tribuna de periodistas<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo viernes 18 de septiembre a las 18 hs. el periodista Christian Sanz disertar\u00e1 en el Instituto de Investigaciones Hist\u00f3ricas Tte. Gral. Juan Domingo Per\u00f3n acerca del siguiente t\u00f3pico: narcotr\u00e1fico y drogas, lo que no se dice. \u00a0\u00a0\u00a0 All\u00ed, Sanz hablar\u00e1 de los efectos de las drogas en general, qui\u00e9nes son los responsables de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[205,203,87,204,206],"class_list":["post-394","post","type-post","status-publish","format-standard","hentry","category-sociedad","tag-christian-sanz","tag-drgas","tag-ley","tag-narcotrafico","tag-periodista"],"_links":{"self":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/comments?post=394"}],"version-history":[{"count":3,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/394\/revisions"}],"predecessor-version":[{"id":397,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/394\/revisions\/397"}],"wp:attachment":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media?parent=394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/categories?post=394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/tags?post=394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}