{"id":18868,"date":"2011-11-20T15:03:06","date_gmt":"2011-11-20T18:03:06","guid":{"rendered":"http:\/\/www.elsindical.com.ar\/notas\/?p=18868"},"modified":"2011-11-20T15:03:06","modified_gmt":"2011-11-20T18:03:06","slug":"limitaron-el-registro-de-las-deudas-financieras-y-sus-informes","status":"publish","type":"post","link":"https:\/\/www.elsindical.com.ar\/notas\/limitaron-el-registro-de-las-deudas-financieras-y-sus-informes\/","title":{"rendered":"Limitaron el registro de las deudas financieras y sus informes"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><a href=\"http:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2011\/11\/informe-deudor.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-18869\" title=\"informe-deudor\" src=\"http:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2011\/11\/informe-deudor.jpg\" alt=\"\" width=\"207\" height=\"276\" \/><\/a>La Corte Suprema confirm\u00f3 que un deudor, <strong>haya pagado o no<\/strong> su deuda, <strong>tiene derecho a que sus datos financieros negativos sean suprimidos<\/strong> del Registro Central de Deudores del Sistema Financiero <strong>una vez que transcurran los plazos que establece la ley.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">El m\u00e1ximo tribunal del pa\u00eds, que preside Ricardo Lorenzetti, estableci\u00f3 en la causa N\u00e1poli contra Citibank que era atendible la pretensi\u00f3n de un hombre que, en 1995 y 1996, hab\u00eda dejado de pagar sus tarjetas Diners y MasterCard, respectivamente.<\/p>\n<p style=\"text-align: justify;\">La sentencia de la Corte, dictada con la aprobaci\u00f3n de sus siete integrantes, dispuso que cinco a\u00f1os despu\u00e9s del \u00faltimo registro desfavorable al deudor, \u00e9ste puede pedir que se supriman las notas de \u00abSituaci\u00f3n 5\u00bb, correspondiente a deuda \u00abirrecuperable\u00bb.<\/p>\n<p style=\"text-align: justify;\">El mecanismo aplicado se llama \u00abderecho al olvido\u00bb y fue establecido por el art\u00edculo 26, inciso 4, de la ley de habeas data: s\u00f3lo se pueden archivar los datos que sean significativos para evaluar la situaci\u00f3n econ\u00f3mico-financiera de una persona, y correspondientes a los \u00faltimos cinco a\u00f1os. Aunque ese plazo se reducir\u00e1 a dos a\u00f1os luego de que el moroso haya pagado lo que adeudaba.<\/p>\n<p style=\"text-align: justify;\">N\u00e1poli reclam\u00f3 la supresi\u00f3n de esa informaci\u00f3n negativa, mientras que Citibank planteaba computar el plazo en una forma que aqu\u00e9l objet\u00f3. Perola Corterecord\u00f3 que en un fallo anterior, dictado en la causa Catania, ya hab\u00eda admitido la existencia de ese derecho al olvido, para que la indagaci\u00f3n sobre el pasado financiero y comercial de una persona no la termine por excluir del circuito comercial.<\/p>\n<p style=\"text-align: justify;\">El banco pretend\u00eda computar el plazo de cinco a\u00f1os desde la fecha de la prescripci\u00f3n, para reclamar el cobro del cr\u00e9dito. Aunque parala Corte, el esp\u00edritu y la letra de la ley -otros pa\u00edses tienen leyes similares, aunque establecen distintos plazos- no fue prorrogar la liberaci\u00f3n del deudor, sino, por el contrario, favorecerla, seg\u00fan recuerda un matutino porte\u00f1o.<\/p>\n<p style=\"text-align: justify;\">En otras palabras, seg\u00fan el tribunal el c\u00f3mputo del plazo debe hacerse desde que qued\u00f3 asentado en el archivo el \u00faltimo dato desfavorable al deudor acerca de la existencia de una deuda exigible. Esto sin que el banco pueda unilateralmente alargar ese plazo reiterando en forma sistem\u00e1tica el mismo dato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Corte Suprema confirm\u00f3 que un deudor, haya pagado o no su deuda, tiene derecho a que sus datos financieros negativos sean suprimidos del Registro Central de Deudores del Sistema Financiero una vez que transcurran los plazos que establece la ley. El m\u00e1ximo tribunal del pa\u00eds, que preside Ricardo Lorenzetti, estableci\u00f3 en la causa N\u00e1poli&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[733,9214,526,87,1125],"class_list":["post-18868","post","type-post","status-publish","format-standard","hentry","category-judiciales","tag-corte-suprema","tag-deudor","tag-informes","tag-ley","tag-registro"],"_links":{"self":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/18868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/comments?post=18868"}],"version-history":[{"count":1,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/18868\/revisions"}],"predecessor-version":[{"id":18870,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/18868\/revisions\/18870"}],"wp:attachment":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media?parent=18868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/categories?post=18868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/tags?post=18868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}