{"id":146763,"date":"2026-09-02T00:01:41","date_gmt":"2026-09-02T03:01:41","guid":{"rendered":"https:\/\/www.elsindical.com.ar\/notas\/?p=146763"},"modified":"2026-09-02T00:01:45","modified_gmt":"2026-09-02T03:01:45","slug":"efemerides-del-dia-2-de-septiembre-15","status":"publish","type":"post","link":"https:\/\/www.elsindical.com.ar\/notas\/efemerides-del-dia-2-de-septiembre-15\/","title":{"rendered":"EFEM\u00c9RIDES: DEL D\u00cdA 2 DE SEPTIEMBRE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u2013 D\u00eda de la Industria (en Argentina)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1519: En Tehucingo (M\u00e9xico), el ej\u00e9rcito del conquistador espa\u00f1ol Hern\u00e1n Cort\u00e9s derrota a los 40.000 hombres de Jicontecal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1587 \u2013 Sale del puerto de Buenos Aires, rumbo al Brasil, la primera exportaci\u00f3n de productos elaborados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1752 \u2013 Gran Breta\u00f1a y sus colonias cambian el calendario al gregoriano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1789 \u2013 El Congreso de los EE.UU. establece el Departamento del Tesoro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1805 \u2013 Nace Esteban Echeverr\u00eda, patriota y poeta que introdujo el Romanticismo en el R\u00edo de la Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1845 \u2013 Muere en C\u00e1diz Bernardino Rivadavia, primer presidente argentino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1870 \u2013 Los franceses se rinden ante los alemanes dando fin a la guerra franco-prusiana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1898 \u2013 Lord Kitchener recupera el Sud\u00e1n para Gran Breta\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1901 \u2013 Theodore Roosevelt pronuncia su famoso discurso \u00abHabla en voz baja y lleva contigo un gran garrote (big stick)\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1937 \u2013 Muere el Bar\u00f3n Pierre de Coubertin, promotor de los Juegos Ol\u00edmpicos de la modernidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1944 \u2013 Ana Frank es enviada a Auschwitz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1945 \u2013 Los japoneses firman la rendici\u00f3n ante el Gral. Mac Arthur a bordo del acorazado Missouri en la Bah\u00eda de Tokyo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1945 \u2013 Ho Chi Minh declara la independencia de Vietnam de Francia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1961 \u2013 Nace Carlos Valderrama, futbolista colombiano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1964 \u2013 Nace el actor Keanu Reeves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1968 \u2013 Nace la actriz mexicana Salma Hayek.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1969 \u2013 Muere Ho Chi Minh, fundador del partido comunista en Indochina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1973 \u2013 Muere J.R.R. Tolkien, novelista brit\u00e1nico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1986 \u2013 Nace Migue Granados, actor y humorista argentino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1987 \u2013 Comienza en Rusia el juicio contra el aviador alem\u00e1n Mathias Rust qui\u00e9n baj\u00f3 sin autorizaci\u00f3n en un avi\u00f3n a la plaza roja de Mosc\u00fa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1988 \u2013 Comienzan en Wembley, Inglaterra, los conciertos de la gira Amnesty International\u2019s Human Rights Now!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2003 \u2013 En Argentina el se promulg\u00f3 la ley 25.779 que declar\u00f3 la nulidad de las leyes de Obediencia Debida y Punto Final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2021 \u2013 Muere Mikis Theodorakis, compositor e intelectual griego.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2013 D\u00eda de la Industria (en Argentina) 1519: En Tehucingo (M\u00e9xico), el ej\u00e9rcito del conquistador espa\u00f1ol Hern\u00e1n Cort\u00e9s derrota a los 40.000 hombres de Jicontecal. 1587 \u2013 Sale del puerto de Buenos Aires, rumbo al Brasil, la primera exportaci\u00f3n de productos elaborados. 1752 \u2013 Gran Breta\u00f1a y sus colonias cambian el calendario al gregoriano. 1789&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[2450,22026],"class_list":["post-146763","post","type-post","status-publish","format-standard","hentry","category-efemerides","tag-diario-el-sindical","tag-efemerides"],"_links":{"self":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/146763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/comments?post=146763"}],"version-history":[{"count":1,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/146763\/revisions"}],"predecessor-version":[{"id":146764,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/146763\/revisions\/146764"}],"wp:attachment":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media?parent=146763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/categories?post=146763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/tags?post=146763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}