{"id":144675,"date":"2026-05-13T00:46:08","date_gmt":"2026-05-13T03:46:08","guid":{"rendered":"https:\/\/www.elsindical.com.ar\/notas\/?p=144675"},"modified":"2026-05-13T00:46:13","modified_gmt":"2026-05-13T03:46:13","slug":"efemerides-del-dia-13-de-mayo-13","status":"publish","type":"post","link":"https:\/\/www.elsindical.com.ar\/notas\/efemerides-del-dia-13-de-mayo-13\/","title":{"rendered":"EFEM\u00c9RIDES: DEL D\u00cdA 13 DE MAYO"},"content":{"rendered":"\n<p>1655 \u2013 Nace el Papa Inocencio XIII.<\/p>\n\n\n\n<p>1717 \u2013 Nace Mar\u00eda Teresa de Austria.<\/p>\n\n\n\n<p>1842 \u2013 Nace Sir Arthur Sullivan, compositor brit\u00e1nico.<\/p>\n\n\n\n<p>1846 \u2013 El Congreso de los EE.UU. declara la Guerra a M\u00e9xico al haber cruzado las tropas de Santa Anna el R\u00edo Grande para reconquistar la independentista Texas.<\/p>\n\n\n\n<p>1854 \u2013 Nace Pedro Bonifacio Palacios \u00abAlmafuerte\u00bb, poeta, maestro y periodista.<\/p>\n\n\n\n<p>1856 \u2013 Nace Peter Henry Emerson, primer fot\u00f3grafo que promovi\u00f3 la fotograf\u00eda como un arte independiente.<\/p>\n\n\n\n<p>1884 \u2013 Muere Cyrus Hall McCormick, inventor estadounidense.<\/p>\n\n\n\n<p>1888 \u2013 Es abolida la esclavitud en Brasil.<\/p>\n\n\n\n<p>1907 \u2013 Nace la novelista inglesa Daphne du Maurier.<\/p>\n\n\n\n<p>1914 \u2013 Nace Joe Louis, boxeador, peso pesado.<\/p>\n\n\n\n<p>1916 \u2013 Muere el escritor Sholem Aleichem, seud\u00f3nimo de Solomon Rabinowitz.<\/p>\n\n\n\n<p>1917 \u2013 La Virgen Mar\u00eda se aparece a tres pastores en F\u00e1tima, Portugal.<\/p>\n\n\n\n<p>1922 \u2013 Nace Marco Denevi, novelista, cuentista, ensayista y comedi\u00f3grafo.<\/p>\n\n\n\n<p>1934 \u2013 Muere el Dr. Angel Gallardo, naturalista y entom\u00f3logo.<\/p>\n\n\n\n<p>1940 \u2013 Primer discurso de Churchill como primer ministro brit\u00e1nico ante la C\u00e1mara de los Lores: \u00abNo tengo nada m\u00e1s que ofrecerles que sangre, dolor y l\u00e1grimas\u00bb.<\/p>\n\n\n\n<p>1941 \u2013 Nace el cantante, compositor y m\u00fasico de rock Ritchie Valens (Ritchie Valenzuela).<\/p>\n\n\n\n<p>1948 \u2013 Nace Pepe Cibri\u00e1n Campoy, actor, director teatral y dramaturgo argentino.<\/p>\n\n\n\n<p>1950 \u2013 Nace Steveland Morris Hardaway, cantante y m\u00fasico, conocido como Stevie Wonder.<\/p>\n\n\n\n<p>1961 \u2013 Muere Gary Cooper, actor estadounidense.<\/p>\n\n\n\n<p>1961 \u2013 Nace Dennis Rodman, \u00abel Gusano\u00bb, basquetbolista de la NBA.<\/p>\n\n\n\n<p>1977 \u2013 Nace Samantha Morton, actriz brit\u00e1nica.<\/p>\n\n\n\n<p>1981 \u2013 Mehmet Ali Agca ataca y hiere al Papa Juan Pablo II con una pistola.<\/p>\n\n\n\n<p>1986 \u2013 Nace Lena Dunham, actriz y directora estadounidense.<\/p>\n\n\n\n<p>1986 \u2013 Nace Robert Pattinson, actor brit\u00e1nico.<\/p>\n\n\n\n<p>1989 \u2013 Grandes grupos de estudiantes&nbsp;ocupan la&nbsp;Plaza Tiananmen&nbsp;y comienzan una huelga de hambre.<\/p>\n\n\n\n<p>1998 \u2013 El juez V\u00edctor Perrota suspende el campeonato oficial de la AFA como consecuencia de la violencia en el f\u00fatbol.<\/p>\n\n\n\n<p>2003 \u2013 Muere Marcos Zucker, actor y humorista argentino.<\/p>\n\n\n\n<p>2012 \u2013 Muere Donald \u00abDuck\u00bb Dunn, bajista estadounidense, de la banda The Blues Brothers.<\/p>\n\n\n\n<p>2012 \u2013 Muere Mario Trejo, escritor argentino.<\/p>\n\n\n\n<p>2014 \u2013 El Tribunal de Justicia de la Uni\u00f3n Europea (TJUE) ordena a los buscadores web eliminar informaci\u00f3n de quien lo solicite por considerarlo dato personal, calificado como \u00abderecho al olvido\u00bb.<\/p>\n\n\n\n<p>2019 \u2013 Muere Doris Day, actriz y cantante estadounidense.<\/p>\n\n\n\n<p>2024 \u2013 Muere Alice Munro, escritora canadiense, primera cuentista ganadora del Premio Nobel de Literatura.<\/p>\n\n\n\n<p>2025 \u2013 Muere Jos\u00e9 \u00abPepe\u00bb Mujica, presidente uruguayo de 2010 a 2015.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1655 \u2013 Nace el Papa Inocencio XIII. 1717 \u2013 Nace Mar\u00eda Teresa de Austria. 1842 \u2013 Nace Sir Arthur Sullivan, compositor brit\u00e1nico. 1846 \u2013 El Congreso de los EE.UU. declara la Guerra a M\u00e9xico al haber cruzado las tropas de Santa Anna el R\u00edo Grande para reconquistar la independentista Texas. 1854 \u2013 Nace Pedro Bonifacio&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[2450,22026],"class_list":["post-144675","post","type-post","status-publish","format-standard","hentry","category-efemerides","tag-diario-el-sindical","tag-efemerides"],"_links":{"self":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/144675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/comments?post=144675"}],"version-history":[{"count":1,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/144675\/revisions"}],"predecessor-version":[{"id":144676,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/144675\/revisions\/144676"}],"wp:attachment":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media?parent=144675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/categories?post=144675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/tags?post=144675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}