{"id":144664,"date":"2026-05-12T14:46:38","date_gmt":"2026-05-12T17:46:38","guid":{"rendered":"https:\/\/www.elsindical.com.ar\/notas\/?p=144664"},"modified":"2026-05-12T14:46:44","modified_gmt":"2026-05-12T17:46:44","slug":"marcha-federal-universitaria-comienzan-a-movilizar-las-columnas","status":"publish","type":"post","link":"https:\/\/www.elsindical.com.ar\/notas\/marcha-federal-universitaria-comienzan-a-movilizar-las-columnas\/","title":{"rendered":"Marcha Federal Universitaria: Comienzan a movilizar las columnas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-03.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"871\" height=\"548\" src=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-03.jpg\" alt=\"\" class=\"wp-image-144665\" srcset=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-03.jpg 871w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-03-300x189.jpg 300w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-03-768x483.jpg 768w\" sizes=\"auto, (max-width: 871px) 100vw, 871px\" \/><\/a><\/figure>\n\n\n\n<p>Las columnas con banderas de organizaciones gremiales y sociales comenzaron a llegar a CABA por la cuarta Marcha Federal Universitaria.<\/p>\n\n\n\n<p><strong>La cuarta Marcha Federal Universitaria se llevar\u00e1 a cabo este martes con el objetivo de exigirle al Gobierno Nacional el cumplimiento de la Ley de Financiamiento Universitario<\/strong>. Comienzan a llegar las distintas columnas.<\/p>\n\n\n\n<p><strong>El acto central ser\u00e1 en Plaza de Mayo a las 17, pero previamente las distintas organizaciones se concentran en diversos puntos.<\/strong> A partir del mediod\u00eda, las columnas comenzaron a movilizar mientras que se espera que aquellos que acuden por su cuenta, arriben a partir de las 16.<\/p>\n\n\n\n<p>La convocatoria a esta movilizaci\u00f3n parti\u00f3 de diversas organizaciones sociales, pol\u00edticas, estudiantiles y docentes, incluyendo al Consejo Interuniversitario Nacional (CIN) y la Federaci\u00f3n Universitaria Argentina (FUA) las cuales denuncian la situaci\u00f3n cr\u00edtica que atraviesan las distintas universidades p\u00fablicas.<\/p>\n\n\n\n<p>Esta cuarta Marcha Federal Universitaria busca visibilizar tambi\u00e9n los bajos sueldos en el sector, por lo que tambi\u00e9n <strong>exigen la recomposici\u00f3n de salarios docentes y no docentes<\/strong>, afectados por la inflaci\u00f3n con haberes percibidos por debajo de la canasta b\u00e1sica.<\/p>\n\n\n\n<p><strong>Hay una ca\u00edda real del 45,6% en las transferencias presupuestarias entre 2023 y 2026. <\/strong>Para los grupos convocantes, esta crisis presupuestaria, que converge en el desfinanciamiento que atraviesa el \u00e1rea educativa, \u201cpone en riesgo el funcionamiento\u201d de todas las universidades nacionales.<\/p>\n\n\n\n<p>Vale recordar que la Ley de Financiamiento Universitario fue votada por el Congreso y\u00a0vetada\u00a0por el Gobierno. Al siguiente a\u00f1o, sucedi\u00f3 exactamente\u00a0lo mismo, pero el Poder Legislativo logr\u00f3\u00a0ratificar\u00a0la iniciativa.\u00a0<strong>Todo termin\u00f3 en la\u00a0Justicia, que fall\u00f3 a favor de las universidades, y ahora el Gobierno\u00a0dilata\u00a0la resoluci\u00f3n acudiendo a la Corte<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-01.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" data-id=\"144666\" src=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-01.jpg\" alt=\"\" class=\"wp-image-144666\" srcset=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-01.jpg 700w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-01-300x169.jpg 300w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-01-460x260.jpg 460w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-02.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"449\" data-id=\"144667\" src=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-02.jpg\" alt=\"\" class=\"wp-image-144667\" srcset=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-02.jpg 700w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2026\/05\/Marcha-Federal-Universitaria-mayo-2026-02-300x192.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Las columnas con banderas de organizaciones gremiales y sociales comenzaron a llegar a CABA por la cuarta Marcha Federal Universitaria. La cuarta Marcha Federal Universitaria se llevar\u00e1 a cabo este martes con el objetivo de exigirle al Gobierno Nacional el cumplimiento de la Ley de Financiamiento Universitario. Comienzan a llegar las distintas columnas. El acto&hellip;<\/p>\n","protected":false},"author":1,"featured_media":144665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[4284,2450,28812,43774,42745],"class_list":["post-144664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","tag-caba","tag-diario-el-sindical","tag-javier-milei","tag-ley-de-financiamiento-universitario","tag-marcha-federal-universitaria"],"_links":{"self":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/144664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/comments?post=144664"}],"version-history":[{"count":1,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/144664\/revisions"}],"predecessor-version":[{"id":144668,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/144664\/revisions\/144668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media\/144665"}],"wp:attachment":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media?parent=144664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/categories?post=144664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/tags?post=144664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}