{"id":118713,"date":"2022-12-08T14:20:51","date_gmt":"2022-12-08T17:20:51","guid":{"rendered":"https:\/\/www.elsindical.com.ar\/notas\/?p=118713"},"modified":"2022-12-08T14:20:52","modified_gmt":"2022-12-08T17:20:52","slug":"murio-a-los-87-anos-pinky","status":"publish","type":"post","link":"https:\/\/www.elsindical.com.ar\/notas\/murio-a-los-87-anos-pinky\/","title":{"rendered":"Muri\u00f3 a los 87 a\u00f1os Pinky"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2022\/12\/Pinky-blanco-y-negro.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"952\" src=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2022\/12\/Pinky-blanco-y-negro.jpg\" alt=\"\" class=\"wp-image-118714\" srcset=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2022\/12\/Pinky-blanco-y-negro.jpg 709w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2022\/12\/Pinky-blanco-y-negro-223x300.jpg 223w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La c\u00e9lebre estrella nacida como Lidia Satragno falleci\u00f3 este jueves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este jueves se confirm\u00f3 la triste noticia de la muerte de <strong>Lidia Satragno<\/strong>, conocida popularmente como <em><strong>Pinky<\/strong><\/em>. Ocurri\u00f3 este mediod\u00eda en su hogar, ten\u00eda 87 a\u00f1os y una destacada trayectoria en el modelaje, la televisi\u00f3n, el cine e incluso en la pol\u00edtica, ya que ocup\u00f3 una banca como diputada nacional entre 2007 y 2011 por la provincia de Buenos Aires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Naci\u00f3 en el 11 de noviembre de 1935 en San Justo y debut\u00f3 en televisi\u00f3n en 1956, luego de un recorrido como modelo de comerciales. Fue su colega\u00a0<strong>Trudy Tinky Tomis <\/strong>quien la rebautiz\u00f3 a <strong>Lidia <\/strong>como <strong>Pinky <\/strong>debido a su piel rosada y dos a\u00f1os m\u00e1s tarde ya estaba conduciendo su propio programa, <em><strong>Buenos d\u00edas Pinky<\/strong><\/em>. Poco despu\u00e9s incursion\u00f3 fugazmente en el cine al integrar el elenco de <em><strong>La ca\u00edda<\/strong><\/em>, dirigida por <strong>Leopoldo Torre Nilsson<\/strong>, en 1959.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El a\u00f1o pasado y en di\u00e1logo con <strong>Teleshow<\/strong>, <strong>Gast\u00f3n Satragno<\/strong>, el hijo que la conductora tuvo durante su relaci\u00f3n con <strong>Ra\u00fal Lavi\u00e9<\/strong>, revel\u00f3 que su mam\u00e1 atravesaba un delicado momento de salud, que generaba mucha preocupaci\u00f3n. \u201cComo le ha pasado a la gran mayor\u00eda de los ancianos de nuestro pa\u00eds, la pandemia les hizo muy mal. Mam\u00e1, antes de la pandemia, todav\u00eda caminaba no mucho, pero caminaba\u2026 y ahora no\u201d, lament\u00f3 Gast\u00f3n. \u201cFue por una cuesti\u00f3n de que no la pod\u00edan atender. Est\u00e1 l\u00facida y de buen \u00e1nimo, pero por las afecciones que ella tiene est\u00e1 postrada y dudo que pueda recuperarse\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Satragno hab\u00eda dado mayores precisiones sobre como encontraba la conductora en esos momentos.\u201c<strong>Est\u00e1 en cama desde hace tiempo y sabe lo que tiene<\/strong>.Cuido a mi mam\u00e1 desde hace a\u00f1os y no tengo ayuda de ning\u00fan tipo, salvo determinados amigos y la familia misma. Yo no cuento absolutamente con nadie siendo mi mam\u00e1 Pinky.<strong> Ni me quiero imaginar la gente que no es Pinky como la debe estar pasando<\/strong>\u201d, sentenci\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde su salida de los medios, Lidia Satragno fue consumiendo los ahorros que hab\u00eda logrado ganar durante su extensa carrera, cuando supo ser la cara de los programas m\u00e1s importantes de la televisi\u00f3n, como la primera transmisi\u00f3n a color en la Argentina. \u201c<strong>Por suerte pude resolver muchos problemas econ\u00f3micos que ten\u00eda y que incid\u00edan en la atenci\u00f3n que yo pod\u00eda darle.<\/strong> Ahora va a tener la atenci\u00f3n que se merece y que le corresponde a nivel m\u00e9dico\u201d, destac\u00f3 Gast\u00f3n, apenado por la situaci\u00f3n que atravesaba su madre.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2022\/12\/Pinky-joven.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"695\" height=\"925\" src=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2022\/12\/Pinky-joven.jpg\" alt=\"\" class=\"wp-image-118715\" srcset=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2022\/12\/Pinky-joven.jpg 695w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2022\/12\/Pinky-joven-225x300.jpg 225w\" sizes=\"auto, (max-width: 695px) 100vw, 695px\" \/><\/a><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La c\u00e9lebre estrella nacida como Lidia Satragno falleci\u00f3 este jueves. Este jueves se confirm\u00f3 la triste noticia de la muerte de Lidia Satragno, conocida popularmente como Pinky. Ocurri\u00f3 este mediod\u00eda en su hogar, ten\u00eda 87 a\u00f1os y una destacada trayectoria en el modelaje, la televisi\u00f3n, el cine e incluso en la pol\u00edtica, ya que ocup\u00f3&hellip;<\/p>\n","protected":false},"author":1,"featured_media":118714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[1507,2450,38936,38935],"class_list":["post-118713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociales","tag-actriz","tag-diario-el-sindical","tag-lidia-satragno","tag-pinky"],"_links":{"self":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/118713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/comments?post=118713"}],"version-history":[{"count":1,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/118713\/revisions"}],"predecessor-version":[{"id":118716,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/118713\/revisions\/118716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media\/118714"}],"wp:attachment":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media?parent=118713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/categories?post=118713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/tags?post=118713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}