{"id":109402,"date":"2021-11-19T08:47:25","date_gmt":"2021-11-19T11:47:25","guid":{"rendered":"https:\/\/www.elsindical.com.ar\/notas\/?p=109402"},"modified":"2021-11-19T08:47:26","modified_gmt":"2021-11-19T11:47:26","slug":"avellaneda-asesinato-en-wilde","status":"publish","type":"post","link":"https:\/\/www.elsindical.com.ar\/notas\/avellaneda-asesinato-en-wilde\/","title":{"rendered":"Avellaneda: Asesinato en Wilde"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2021\/11\/asesinato-en-Wilde.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"949\" height=\"540\" src=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2021\/11\/asesinato-en-Wilde.jpg\" alt=\"\" class=\"wp-image-109403\" srcset=\"https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2021\/11\/asesinato-en-Wilde.jpg 949w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2021\/11\/asesinato-en-Wilde-300x171.jpg 300w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2021\/11\/asesinato-en-Wilde-768x437.jpg 768w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2021\/11\/asesinato-en-Wilde-500x285.jpg 500w, https:\/\/www.elsindical.com.ar\/notas\/var\/www\/html\/notas\/wp-content\/uploads\/2021\/11\/asesinato-en-Wilde-220x126.jpg 220w\" sizes=\"auto, (max-width: 949px) 100vw, 949px\" \/><\/a><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>El homicidio se produjo en la localidad bonaerense de Wilde y la v\u00edctima era una persona\u00a0de 38 a\u00f1os. Los efectivos policiales\u00a0 buscan al criminal.<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Un hombre, de 38 a\u00f1os, fue asesinado a balazos por un vendedor de drogas, a quien increp\u00f3 porque, momentos antes, el criminal hab\u00eda amenazado a su hijastro. El caso sucedi\u00f3 en la localidad bonaerense de Wilde y el homicida, que logr\u00f3 darse a la fuga, es buscado de manera intensa por los pesquisas policiales. Familiares de la v\u00edctima reclamaron justicia y que el episodio no quede en la impunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los voceros del departamento judicial de Avellaneda &#8211; Lan\u00fas revelaron a<strong><em> cronica.com.ar <\/em><\/strong>que la v\u00edctima del il\u00edcito fue identificada como <strong>Mohamed Ali Ojeda<\/strong>, de 38 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a lo manifestado por los informantes, los hechos, que ocurrieron d\u00edas pasados, pero que se conocieron en la jornada de hoy, comenzaron cuando un joven mantuvo un altercado con el delincuente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Momentos despu\u00e9s, el muchacho les explic\u00f3 lo sucedido a sus familiares, afirm\u00e1ndoles que el malviviente lo hab\u00eda amenazado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como consecuencia de esta situaci\u00f3n, el padrastro del joven concurri\u00f3 a buscar al marginal, a quien localiz\u00f3 en las inmediaciones del cruce de Pino y Mart\u00edn Fierro y de un complejo de edificios, oportunidad en la que se gener\u00f3 una disputa callejera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Habitantes del mencionado vecindario se\u00f1alaron que la discusi\u00f3n finaliz\u00f3 en tragedia, porque el asesino, que se asegura tiene 25 a\u00f1os, extrajo un arma de fuego, con la que agredi\u00f3 a disparos a la v\u00edctima, quien padeci\u00f3 heridas de gravedad en la regi\u00f3n tor\u00e1cica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con rapidez, el atacante huy\u00f3 y se escondi\u00f3 en las calles del barrio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ojeda tuvo que ser trasladado, de urgencia, a un centro asistencial de dicha zona, en el sur del conurbano provincial, aunque posteriormente dej\u00f3 de existir, a pesar de la tarea desarrollada por los m\u00e9dicos del nosocomio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a los diversos aportados por gente del lugar, integrantes de la comisar\u00eda de Wilde (5\u00aa de Avellaneda) realizan diferentes procedimientos\u00a0 en el citado distrito, con el objetivo de averiguar el paradero del responsable del crimen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, los miembros de la seccional intentan averiguar cu\u00e1les fueron los motivos que originaron el altercado que hab\u00edan entablado el asesino y el hijastro de la v\u00edctima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El homicidio se produjo en la localidad bonaerense de Wilde y la v\u00edctima era una persona\u00a0de 38 a\u00f1os. Los efectivos policiales\u00a0 buscan al criminal. Un hombre, de 38 a\u00f1os, fue asesinado a balazos por un vendedor de drogas, a quien increp\u00f3 porque, momentos antes, el criminal hab\u00eda amenazado a su hijastro. El caso sucedi\u00f3 en&hellip;<\/p>\n","protected":false},"author":1,"featured_media":109403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[461,2450,2329,35950,881,882],"class_list":["post-109402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales","tag-avellaneda","tag-diario-el-sindical","tag-homicidio","tag-mohamed-ali-ojeda","tag-pelea","tag-wilde"],"_links":{"self":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/109402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/comments?post=109402"}],"version-history":[{"count":1,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/109402\/revisions"}],"predecessor-version":[{"id":109404,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/posts\/109402\/revisions\/109404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media\/109403"}],"wp:attachment":[{"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/media?parent=109402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/categories?post=109402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsindical.com.ar\/notas\/wp-json\/wp\/v2\/tags?post=109402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}